{"id":78286,"date":"2021-05-02T07:24:50","date_gmt":"2021-05-02T11:24:50","guid":{"rendered":"https:\/\/taxitaxiapp.com\/sitio\/index.php\/2021\/05\/02\/trabajo-en-san-agustin\/"},"modified":"2021-05-02T07:24:50","modified_gmt":"2021-05-02T11:24:50","slug":"trabajo-en-san-agustin","status":"publish","type":"post","link":"https:\/\/taxitaxiapp.com\/sitio\/index.php\/2021\/05\/02\/trabajo-en-san-agustin\/","title":{"rendered":"Trabajo en San Agust\u00edn"},"content":{"rendered":"<p><strong>\u00a1\u00c9xito!<\/strong> Parece que est\u00e1s buscando Trabajo en San Agust\u00edn. Con<strong> Taxi-Taxi App<\/strong>, puedes utilizar tu Carro, Moto, Bicicleta, para hacer Servicios de Transporte: Taxi, Delivery, y otros&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Trabaja de Forma independiente<\/strong>, tomando solicitudes de servicio de transporte. Gana dinero extra, sin tener que dejar lo que haces actualmente. <strong>Taxi-Taxi<\/strong>, te permite conseguir servicios desde la comodidad de tu casa, sin consumir exceso de combustible, recorriendo toda la zona de San Agust\u00edn. T\u00fa decides qu\u00e9 servicios te conviene tomar. Ten el control de tu negocio. Gana tambi\u00e9n por los servicios que hagan los conductores invitador por t\u00ed.<\/p>\n<p>&nbsp;<\/p>\n<p>Si a\u00fan no perteneces a la Red de Conductores Validados de San Agust\u00edn, te invitamos a descargar ahora, la aplicaci\u00f3n en tu dispositivo m\u00f3vil. <a href=\"https:\/\/taxitaxiapp.com\/conductor\">https:\/\/taxitaxiapp.com\/conductor\u00a0<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Comparte <a href=\"https:\/\/taxitaxiapp.com\/cliente\">Taxi-Taxi App<\/a>, para tener muchos clientes y hacer muchos servicios.<\/p>\n<p>&nbsp;<\/p>\n<p>Te esperamos.<\/p>\n<p><strong>El Equipo Taxi-Taxi<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1\u00c9xito! Parece que est\u00e1s buscando Trabajo en San Agust\u00edn. Con Taxi-Taxi App, puedes utilizar tu Carro, Moto, Bicicleta, para hacer Servicios de Transporte: Taxi, Delivery, y otros&#8230; &nbsp; Trabaja de Forma independiente, tomando solicitudes de servicio de transporte. Gana dinero extra, sin tener que dejar lo que haces actualmente. Taxi-Taxi, te permite conseguir servicios desde [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":77162,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[16],"tags":[231,927],"_links":{"self":[{"href":"https:\/\/taxitaxiapp.com\/sitio\/index.php\/wp-json\/wp\/v2\/posts\/78286"}],"collection":[{"href":"https:\/\/taxitaxiapp.com\/sitio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/taxitaxiapp.com\/sitio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/taxitaxiapp.com\/sitio\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/taxitaxiapp.com\/sitio\/index.php\/wp-json\/wp\/v2\/comments?post=78286"}],"version-history":[{"count":0,"href":"https:\/\/taxitaxiapp.com\/sitio\/index.php\/wp-json\/wp\/v2\/posts\/78286\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/taxitaxiapp.com\/sitio\/index.php\/wp-json\/wp\/v2\/media\/77162"}],"wp:attachment":[{"href":"https:\/\/taxitaxiapp.com\/sitio\/index.php\/wp-json\/wp\/v2\/media?parent=78286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/taxitaxiapp.com\/sitio\/index.php\/wp-json\/wp\/v2\/categories?post=78286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/taxitaxiapp.com\/sitio\/index.php\/wp-json\/wp\/v2\/tags?post=78286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}